{"id":362,"date":"2023-07-27T11:09:07","date_gmt":"2023-07-27T11:09:07","guid":{"rendered":"https:\/\/ktwgroup.ge\/wine\/%e1%83%a5%e1%83%98%e1%83%9c%e1%83%ab%e1%83%9b%e1%83%90%e1%83%a0%e1%83%90%e1%83%a3%e1%83%9a%e1%83%98-2\/"},"modified":"2026-06-09T11:51:45","modified_gmt":"2026-06-09T11:51:45","slug":"kindzmarauli-8","status":"publish","type":"wine","link":"https:\/\/ktwgroup.ge\/en\/wine\/kindzmarauli-8\/","title":{"rendered":"\u10e5\u10d8\u10dc\u10eb\u10db\u10d0\u10e0\u10d0\u10e3\u10da\u10d8"},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false},"wine-manufacturer":[12],"class_list":["post-362","wine","type-wine","status-publish","hentry","wine-manufacturer-maghlari"],"acf":[],"_links":{"self":[{"href":"https:\/\/ktwgroup.ge\/en\/wp-json\/wp\/v2\/wine\/362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ktwgroup.ge\/en\/wp-json\/wp\/v2\/wine"}],"about":[{"href":"https:\/\/ktwgroup.ge\/en\/wp-json\/wp\/v2\/types\/wine"}],"version-history":[{"count":1,"href":"https:\/\/ktwgroup.ge\/en\/wp-json\/wp\/v2\/wine\/362\/revisions"}],"predecessor-version":[{"id":512,"href":"https:\/\/ktwgroup.ge\/en\/wp-json\/wp\/v2\/wine\/362\/revisions\/512"}],"wp:attachment":[{"href":"https:\/\/ktwgroup.ge\/en\/wp-json\/wp\/v2\/media?parent=362"}],"wp:term":[{"taxonomy":"wine-manufacturer","embeddable":true,"href":"https:\/\/ktwgroup.ge\/en\/wp-json\/wp\/v2\/wine-manufacturer?post=362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}