{"id":209,"date":"2023-03-31T07:40:15","date_gmt":"2023-03-31T07:40:15","guid":{"rendered":"https:\/\/ktwgroup.ge\/wine\/premium-chinuri\/"},"modified":"2026-06-09T11:49:39","modified_gmt":"2026-06-09T11:49:39","slug":"premium-chinuri","status":"publish","type":"wine","link":"https:\/\/ktwgroup.ge\/ru\/wine\/premium-chinuri\/","title":{"rendered":"\u10ee\u10d5\u10d0\u10dc\u10ed\u10d9\u10d0\u10e0\u10d0"},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":68,"template":"","meta":{"_acf_changed":false},"wine-manufacturer":[2],"class_list":["post-209","wine","type-wine","status-publish","hentry","wine-manufacturer-special-collection"],"acf":[],"_links":{"self":[{"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/wine\/209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/wine"}],"about":[{"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/types\/wine"}],"version-history":[{"count":1,"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/wine\/209\/revisions"}],"predecessor-version":[{"id":435,"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/wine\/209\/revisions\/435"}],"wp:attachment":[{"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/media?parent=209"}],"wp:term":[{"taxonomy":"wine-manufacturer","embeddable":true,"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/wine-manufacturer?post=209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}