{"id":286,"date":"2023-04-07T10:42:04","date_gmt":"2023-04-07T10:42:04","guid":{"rendered":"https:\/\/ktwgroup.ge\/wine\/khvanchkara-2\/"},"modified":"2026-06-09T11:50:37","modified_gmt":"2026-06-09T11:50:37","slug":"khvanchkara-2","status":"publish","type":"wine","link":"https:\/\/ktwgroup.ge\/ru\/wine\/khvanchkara-2\/","title":{"rendered":"\u10ee\u10d5\u10d0\u10dc\u10ed\u10d9\u10d0\u10e0\u10d0"},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":27,"template":"","meta":{"_acf_changed":false},"wine-manufacturer":[7],"class_list":["post-286","wine","type-wine","status-publish","hentry","wine-manufacturer-old-kakheti"],"acf":[],"_links":{"self":[{"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/wine\/286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/wine"}],"about":[{"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/types\/wine"}],"version-history":[{"count":1,"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/wine\/286\/revisions"}],"predecessor-version":[{"id":474,"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/wine\/286\/revisions\/474"}],"wp:attachment":[{"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/media?parent=286"}],"wp:term":[{"taxonomy":"wine-manufacturer","embeddable":true,"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/wine-manufacturer?post=286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}