{"id":572,"date":"2026-05-27T10:47:06","date_gmt":"2026-05-27T10:47:06","guid":{"rendered":"https:\/\/ktwgroup.ge\/wine\/%e1%83%90%e1%83%9a%e1%83%90%e1%83%96%e1%83%9c%e1%83%98%e1%83%a1-%e1%83%95%e1%83%94%e1%83%9a%e1%83%98-11\/"},"modified":"2026-05-27T10:47:06","modified_gmt":"2026-05-27T10:47:06","slug":"alaznis-veli-2","status":"publish","type":"wine","link":"https:\/\/ktwgroup.ge\/ru\/wine\/alaznis-veli-2\/","title":{"rendered":"\u10d0\u10da\u10d0\u10d6\u10dc\u10d8\u10e1 \u10d5\u10d4\u10da\u10d8"},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false},"wine-manufacturer":[16],"class_list":["post-572","wine","type-wine","status-publish","hentry","wine-manufacturer-sazandari"],"acf":[],"_links":{"self":[{"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/wine\/572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/wine"}],"about":[{"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/types\/wine"}],"version-history":[{"count":0,"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/wine\/572\/revisions"}],"wp:attachment":[{"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/media?parent=572"}],"wp:term":[{"taxonomy":"wine-manufacturer","embeddable":true,"href":"https:\/\/ktwgroup.ge\/ru\/wp-json\/wp\/v2\/wine-manufacturer?post=572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}