{"id":311,"date":"2023-04-07T11:00:19","date_gmt":"2023-04-07T11:00:19","guid":{"rendered":"https:\/\/ktwgroup.ge\/wine\/tsinandali-2\/"},"modified":"2026-06-09T11:50:57","modified_gmt":"2026-06-09T11:50:57","slug":"tsinandali-2","status":"publish","type":"wine","link":"https:\/\/ktwgroup.ge\/zh\/wine\/tsinandali-2\/","title":{"rendered":"\u10ec\u10d8\u10dc\u10d0\u10dc\u10d3\u10d0\u10da\u10d8"},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":15,"template":"","meta":{"_acf_changed":false},"wine-manufacturer":[7],"class_list":["post-311","wine","type-wine","status-publish","hentry","wine-manufacturer-old-kakheti"],"acf":[],"_links":{"self":[{"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/wine\/311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/wine"}],"about":[{"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/types\/wine"}],"version-history":[{"count":1,"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/wine\/311\/revisions"}],"predecessor-version":[{"id":486,"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/wine\/311\/revisions\/486"}],"wp:attachment":[{"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/media?parent=311"}],"wp:term":[{"taxonomy":"wine-manufacturer","embeddable":true,"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/wine-manufacturer?post=311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}