{"id":368,"date":"2023-07-27T11:43:19","date_gmt":"2023-07-27T11:43:19","guid":{"rendered":"https:\/\/ktwgroup.ge\/wine\/%e1%83%90%e1%83%9a%e1%83%90%e1%83%96%e1%83%9c%e1%83%98%e1%83%a1-%e1%83%95%e1%83%94%e1%83%9a%e1%83%98-6\/"},"modified":"2026-06-09T11:51:48","modified_gmt":"2026-06-09T11:51:48","slug":"alaznis-veli-7","status":"publish","type":"wine","link":"https:\/\/ktwgroup.ge\/zh\/wine\/alaznis-veli-7\/","title":{"rendered":"\u10d0\u10da\u10d0\u10d6\u10dc\u10d8\u10e1 \u10d5\u10d4\u10da\u10d8"},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false},"wine-manufacturer":[13],"class_list":["post-368","wine","type-wine","status-publish","hentry","wine-manufacturer-tabla-kartuli-ghvino"],"acf":[],"_links":{"self":[{"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/wine\/368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/wine"}],"about":[{"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/types\/wine"}],"version-history":[{"count":1,"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/wine\/368\/revisions"}],"predecessor-version":[{"id":515,"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/wine\/368\/revisions\/515"}],"wp:attachment":[{"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/media?parent=368"}],"wp:term":[{"taxonomy":"wine-manufacturer","embeddable":true,"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/wine-manufacturer?post=368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}