{"id":416,"date":"2025-07-02T08:24:51","date_gmt":"2025-07-02T08:24:51","guid":{"rendered":"https:\/\/ktwgroup.ge\/wine\/%e1%83%a1%e1%83%90%e1%83%a4%e1%83%94%e1%83%a0%e1%83%90%e1%83%95%e1%83%98-%e1%83%a0%e1%83%9d%e1%83%96%e1%83%94\/"},"modified":"2026-06-09T11:52:19","modified_gmt":"2026-06-09T11:52:19","slug":"saperavi-roze","status":"publish","type":"wine","link":"https:\/\/ktwgroup.ge\/zh\/wine\/saperavi-roze\/","title":{"rendered":"\u10e1\u10d0\u10e4\u10d4\u10e0\u10d0\u10d5\u10d8 \u10e0\u10dd\u10d6\u10d4"},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false},"wine-manufacturer":[5],"class_list":["post-416","wine","type-wine","status-publish","hentry","wine-manufacturer-chateau-manavi"],"acf":[],"_links":{"self":[{"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/wine\/416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/wine"}],"about":[{"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/types\/wine"}],"version-history":[{"count":1,"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/wine\/416\/revisions"}],"predecessor-version":[{"id":540,"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/wine\/416\/revisions\/540"}],"wp:attachment":[{"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/media?parent=416"}],"wp:term":[{"taxonomy":"wine-manufacturer","embeddable":true,"href":"https:\/\/ktwgroup.ge\/zh\/wp-json\/wp\/v2\/wine-manufacturer?post=416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}